{"id":303,"date":"2006-06-10T14:21:25","date_gmt":"2006-06-10T12:21:25","guid":{"rendered":"http:\/\/lehrerrundmail.de\/wordpress\/index.php\/2006\/06\/11\/lehrerrundmail-082006\/"},"modified":"2006-06-10T14:21:25","modified_gmt":"2006-06-10T12:21:25","slug":"lehrerrundmail-082006","status":"publish","type":"post","link":"https:\/\/lehrerrundmail.de\/wordpress\/2006\/lehrerrundmail-082006\/","title":{"rendered":"Lehrerrundmail 08\/2006"},"content":{"rendered":"<p>Nachdem es sich nun auch bis ins mittelfr\u00e4nkische Bayern herumgesprochen hat, dass nicht jeder Lehrer momentan die Pfingstferien genie\u00dfen darf, habe ich f\u00fcr all jene, die bei WM und Superwetter arbeiten m\u00fcssen, eine neue Ausgabe der Lehrerrundmail vorbereitet. Sonniges Surfen w\u00fcnscht<br \/>\n&nbsp;&nbsp;<em>Holger<\/em><\/p>\n<p><strong>Arbeitsbl\u00e4tter zum WissenskanonGeschichte<\/strong><br \/>\nDen WissenskanonGeschichte habe ich ja schon vorgestellt und beim &#8222;Lehrerfreund&#8220; hat sich auch bereits eine kleiner Disput \u00fcber dessen Sinnhaftigkeit entwickelt. Dessen ungeachtet legt der Autor Christoph Pallaske nach und hat ein kleines Paket aus handlungsorientierten, thematischen Arbeitsbl\u00e4ttern geschn\u00fcrt, das er kostenlos zum Download als PDF-Dokument anbietet. Meiner (unma\u00dfgeblichen, da geschichtsdidaktisch und -wissenschaftlich reichlich unbeleckten) Meinung nach, ein durchaus hilfreiches Arbeitsmaterial zum Umgang mit dem &#8218;Wissenskanon&#8216;.<br \/>\n<a href=\"http:\/\/www.thussie.de\/ger\/pdf\/unterricht\/materialien\/geschichte\/wika-arbeitsblaetter.pdf\">http:\/\/www.thussie.de\/[&#8230;]\/wika-arbeitsblaetter.pdf<\/a><\/p>\n<p><strong>Kunst unterrichten<\/strong><br \/>\nHauptschullehrer werden auch gerne als Zehnk\u00e4mpfer bezeichnet, d\u00fcrfen sie doch mindestens zehn verschiedene F\u00e4cher unterrichten, von denen sie vielleicht drei studiert haben. Insbesondere beim Kunstunterricht fehlen da manchmal gute Ideen und praktische Umsetzungsm\u00f6glichkeiten. Abhilfe m\u00f6chte hier die Loseblattsammlung &#8222;Kunst unterrichten &#8211; motivierend, lebendig, methodisch vielf\u00e4ltig!&#8220; schaffen. <em>Weiterlesen:<\/em><br \/>\n<a href=\"http:\/\/www.lehrerrundmail.de\/url\/?kunstunterrichten\">http:\/\/www.lehrerrundmail.de\/url\/?kunstunterrichten<\/a><\/p>\n<p><center><br \/>\n<!-- BEGIN PARTNER PROGRAM - DO NOT CHANGE THE PARAMETERS OF THE HYPERLINK --><br \/>\n<a href=\"http:\/\/partners.webmasterplan.com\/click.asp?ref=218927&#038;site=1879&#038;type=b2&#038;bnb=2\"  target=\"_blank\"><br \/>\n<img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/banners.webmasterplan.com\/view.asp?ref=218927&#038;site=1879&#038;b=2\" border=\"0\" alt=\"Tchibo.de - Jede Woche eine neue Welt!\" width=\"234\" height=\"60\"\/><\/a><br \/>\n<!-- END PARTNER PROGRAM --><br \/>\n<\/center><\/p>\n<p><strong>Rechtsf\u00e4lle aus dem Schulalltag<\/strong><br \/>\n\u00dcber 200 Rechtsf\u00e4lle aus dem Schulalltag hat das Bayerische Kultusministerium auf seinen Schulberatungsseiten gesammelt. &#8222;Die Antworten auf die Anfragen der Sch\u00fcler und Eltern sind rechtsverbindlich&#8220; und decken Bereiche wie Unterschleif, Toilettengang, Hausaufgaben und vieles mehr ab.<br \/>\n<a href=\"http:\/\/www.km.bayern.de\/km\/rat%5Fauskunft\/schulberatung\/rechtsfaelle\/\">http:\/\/www.km.bayern.de\/km\/rat%5Fauskunft\/schulberatung\/rechtsfaelle\/<\/a><\/p>\n<p><strong>Christoph Kolumbus<\/strong><br \/>\nAm 20. Mai j\u00e4hrte sich der Todestag von Christoph Kolumbus zum f\u00fcnfhundertsten Mal. Der Deutsche Bildungsserver hat zu diesem Anlass ein Dossier mit verschiedensten Materialien, Quellen, biographischen Angaben, etc. gesammelt. Insbesondere die Seite mit den Unterrichtsmaterialien erm\u00f6glicht einen direkten Einsatz im Unterricht.<br \/>\n<a href=\"http:\/\/www.bildungsserver.de\/zeigen.html?seite=4294\">http:\/\/www.bildungsserver.de\/zeigen.html?seite=4294<\/a><\/p>\n<p><strong>Dr. Web-Buch gratis<\/strong><br \/>\nSchon lange gelten die Seiten von Dr. Web f\u00fcr diejenigen, die sich mit dem Basteln eigener Webseiten befassen, als hilfreiche Quelle f\u00fcr Tipps und Tricks. Nun ist das &#8222;Dr. Web Buch 5&#8220; erschienen, das f\u00fcr 18,90 EUR im Dr. Web-Shop bestellt werden kann. Wer&#8217;s lieber gratis, aber daf\u00fcr nur als PDF-Dokument h\u00e4tte, kann das Buch, das Themen wie Webdesign, Suchmaschinen, Google AdSense, etc. behandelt, hier herunterladen:<br \/>\n<a href=\"http:\/\/www.drweb.de\/weblog\/weblog\/?p=564\">http:\/\/www.drweb.de\/weblog\/weblog\/?p=564<\/a><\/p>\n<p><strong>Knigge &#8211; der erste Eindruck z\u00e4hlt<\/strong><br \/>\nAnhand eines typischen Tagesablaufs im &#8222;Business&#8220; (es muss heute ja englisch sein) f\u00fchrt der Online Ratgeber Knigge des Bildungsforums S\u00fcdwestsachsen in das gute Benehmen bei gesch\u00e4ftlichen Anl\u00e4ssen ein. Vom Schreiben einer E-Mail bis zum richtigen Verhalten beim Smalltalk am kalten Buffet werden alle wichtigen Stolpersteine beim Berufseinstieg kurz und b\u00fcndig angesprochen.<br \/>\n<a href=\"http:\/\/www.tu-chemnitz.de\/phil\/ebbw\/bf\/bf_elearning\/3\/index.html\">http:\/\/www.tu-chemnitz.de\/phil\/ebbw\/bf\/bf_elearning\/3\/index.html<\/a><\/p>\n<p><center><br \/>\n<!-- BEGIN PARTNER PROGRAM - DO NOT CHANGE THE PARAMETERS OF THE HYPERLINK --><br \/>\n<a href=\"http:\/\/partners.webmasterplan.com\/click.asp?ref=218927&#038;site=1860&#038;type=b34&#038;bnb=34\"  target=\"_blank\"><br \/>\n<img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/banners.webmasterplan.com\/view.asp?ref=218927&#038;site=1860&#038;b=34\" border=\"0\" alt=\"VistaPrint - Gratis-Visitenkarten und mehr\" width=\"468\" height=\"60\"\/><\/a><br \/>\n<!-- END PARTNER PROGRAM --><br \/>\n<\/center><\/p>\n<p><strong>Logisch &#8211; Die Denk-Boxx<\/strong><br \/>\nEine nette Kompilation f\u00fcnf verschiedener Denk- und Knobelspiele hat Halycon-Media herausgebracht. Unter dem Namen &#8222;Logisch &#8211; Die Denk-Boxx Vol. 1&#8220; versammeln sich Crazy Machines (das ich bereits in der Vergangenheit sehr loben musste), Bridge Builder (virtuelle Br\u00fcckenarchitektur), WinSudoku (unz\u00e4hlige Sudoku-R\u00e4tsel mit eingebautem Assistenten), Fritz 8 SE (bekanntes und spielstarkes Schachprogramm mit Anf\u00e4ngerlehrgang) und schlie\u00dflich als Bonus das Kugel-Knobelspiel Enigma. Bei einem Preis von 19,95 EUR sicher eine sinnvolle Investition in unz\u00e4hlige Knobel- und Bastelstunden am PC.<br \/>\n<a href=\"http:\/\/halycon.de\/index.php?templateid=news&#038;id=38\">Informationen bei Halycon<\/a><br \/>\n<a href=\"http:\/\/www.amazon.de\/exec\/obidos\/ASIN\/B000EMSP6A\/lehrerrundmai-21\">Bestellen bei Amazon<\/a><\/p>\n<p>Drei Ausgaben der Denk-Boxx darf ich unter den Lesern der Lehrerrundmail verlosen. Zum Mitspielen einfach die eigene E-Mail-Adresse in diesem Formular eintragen:<br \/>\n<a href=\"http:\/\/lehrerrundmail.de\/wordpress\/index.php\/gewinnspiel\/\">http:\/\/lehrerrundmail.de\/wordpress\/index.php\/gewinnspiel\/<\/a><\/p>\n<p>Sollten bei zu langen Links Probleme auftreten, empfehle ich wie immer den Besuch der Lehrerrundmail-Seiten. Dort steht jeder Artikel komplett verlinkt zum Abruf bereit!<br \/>\n<a href=\"http:\/\/www.lehrerrundmail.de\">http:\/\/www.lehrerrundmail.de<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Nachdem es sich nun auch bis ins mittelfr\u00e4nkische Bayern herumgesprochen hat, dass nicht jeder Lehrer momentan die Pfingstferien genie\u00dfen darf, habe ich f\u00fcr all jene, die bei WM und Superwetter arbeiten m\u00fcssen, eine neue Ausgabe<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-303","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/lehrerrundmail.de\/wordpress\/wp-json\/wp\/v2\/posts\/303","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lehrerrundmail.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lehrerrundmail.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lehrerrundmail.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lehrerrundmail.de\/wordpress\/wp-json\/wp\/v2\/comments?post=303"}],"version-history":[{"count":0,"href":"https:\/\/lehrerrundmail.de\/wordpress\/wp-json\/wp\/v2\/posts\/303\/revisions"}],"wp:attachment":[{"href":"https:\/\/lehrerrundmail.de\/wordpress\/wp-json\/wp\/v2\/media?parent=303"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lehrerrundmail.de\/wordpress\/wp-json\/wp\/v2\/categories?post=303"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lehrerrundmail.de\/wordpress\/wp-json\/wp\/v2\/tags?post=303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}